{"id":18621,"date":"2022-09-24T06:50:48","date_gmt":"2022-09-23T19:20:48","guid":{"rendered":"http:\/\/www.hondurasensusmanos.com\/turismo\/?p=18621"},"modified":"2022-07-19T05:54:29","modified_gmt":"2022-07-18T18:24:29","slug":"el-24-de-septiembre-el-municipio-de-veracruz-copan-celebra-en-honor-a-la-virgen-de-la-merced","status":"publish","type":"post","link":"http:\/\/www.hondurasensusmanos.com\/turismo\/el-24-de-septiembre-el-municipio-de-veracruz-copan-celebra-en-honor-a-la-virgen-de-la-merced\/","title":{"rendered":"El 24 de septiembre el municipio de Veracruz, Copan celebra en honor a la virgen de la Merced"},"content":{"rendered":"<p><a href=\"http:\/\/www.hondurasensusmanos.com\/turismo\/wp-content\/uploads\/2021\/06\/veracruz-copan.jpg\"><img loading=\"lazy\" class=\"size-full wp-image-18622 alignleft\" src=\"http:\/\/www.hondurasensusmanos.com\/turismo\/wp-content\/uploads\/2021\/06\/veracruz-copan.jpg\" alt=\"\" width=\"300\" height=\"168\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Veracruz<\/strong>\u00a0es una\u00a0municipalidad\u00a0en el\u00a0departamento\u00a0de\u00a0Cop\u00e1n, en la rep\u00fablica de\u00a0Honduras.<\/p>\n<p style=\"text-align: justify;\">En la Divisi\u00f3n Pol\u00edtica de 1896 figuraba como Aldea del Municipio de San Jos\u00e9; antiguamente era la Aldea de Quetuna; el 3 de junio de 1902, los vecinos de dicha Aldea piden la creaci\u00f3n de un nuevo Municipio, Erigese en Municipio la Aldea de Veracruz, comprendida en la jurisdicci\u00f3n de San Jos\u00e9, Departamento de Cop\u00e1n.<\/p>\n<p style=\"text-align: justify;\">El municipio colinda al norte con los municipios de\u00a0Trinidad de Cop\u00e1n\u00a0y\u00a0San Jos\u00e9, al sur con el municipio de\u00a0Santa Rosa de Cop\u00e1n, al este con los municipios de Santa Rosa y San Jos\u00e9 y al oeste con el municipio de\u00a0Dolores. Est\u00e1 situado en la parte central del departamento y su cabecera, el pueblo de Veracruz, situado en el Valle de Quetuna y en la base sur del Cerr\u00f3n.<\/p>\n<p><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe class='youtube-player' width='618' height='348' src='https:\/\/www.youtube.com\/embed\/Gdz4mCDitYg?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=es-ES&#038;autohide=2&#038;wmode=transparent' allowfullscreen='true' style='border:0;' sandbox='allow-scripts allow-same-origin allow-popups allow-presentation'><\/iframe><\/span><\/p>\n<p><strong>Virgen de la Merced<a href=\"http:\/\/www.hondurasensusmanos.com\/turismo\/wp-content\/uploads\/2021\/06\/virgend-de-la-merced.jpg\"><img loading=\"lazy\" class=\"size-full wp-image-18597 alignright\" src=\"http:\/\/www.hondurasensusmanos.com\/turismo\/wp-content\/uploads\/2021\/06\/virgend-de-la-merced.jpg\" alt=\"\" width=\"199\" height=\"300\" \/><\/a><\/strong><\/p>\n<p style=\"text-align: justify;\">La\u00a0<strong><em>Virgen de la Merced<\/em><\/strong>\u00a0o\u00a0<strong>Nuestra Se\u00f1ora de las Mercedes<\/strong>\u00a0es una\u00a0advocaci\u00f3n mariana\u00a0venerada por los\u00a0cat\u00f3licos\u00a0de la\u00a0Bienaventurada Virgen Mar\u00eda. Es equivalente tambi\u00e9n el nombre de\u00a0<strong>Virgen de la Misericordia<\/strong>. Su fiesta se celebra el d\u00eda\u00a024 de septiembre.<\/p>\n<p style=\"text-align: justify;\">Esta advocaci\u00f3n tiene su inicio, cuando la Virgen Mar\u00eda \u2014en su advocaci\u00f3n de Virgen de la Merced\u2014 se apareci\u00f3 por separado a tres ilustres personajes: a\u00a0San Pedro Nolasco, quien ser\u00eda el fundador de la\u00a0Orden de la Merced; al rey\u00a0Jaime I de Arag\u00f3n, conocido como \u00abel conquistador\u00bb, y reinante en aquel momento en la\u00a0Corona de Arag\u00f3n; y a\u00a0San Raimundo de Pe\u00f1afort, fraile dominico, maestro general de su orden de predicadores, y confesor del primero. Diez d\u00edas despu\u00e9s de la aparici\u00f3n, los tres caballeros se encontraron en la\u00a0Catedral de Barcelona\u00a0y compartieron haber tenido la misma aparici\u00f3n: la Virgen Mar\u00eda les ped\u00eda la fundaci\u00f3n de una orden religiosa dedicada a la redenci\u00f3n de los cautivos. Ser\u00eda la\u00a0Orden de la Merced\u00a0para la redenci\u00f3n de los cautivos<\/p>\n<p style=\"text-align: justify;\">La devoci\u00f3n a la Virgen de la Merced se difundi\u00f3 muy pronto por\u00a0Catalu\u00f1a\u00a0y de ah\u00ed al resto de\u00a0Espa\u00f1a, por\u00a0Francia\u00a0y por\u00a0Italia, a partir del\u00a0siglo XIII\u00a0con la labor de redenci\u00f3n de estos religiosos y sus cofrades. Con la Evangelizaci\u00f3n de Am\u00e9rica, en la que la\u00a0Orden de la Merced\u00a0particip\u00f3 desde sus mismos inicios, la devoci\u00f3n se extendi\u00f3 y arraig\u00f3 profundamente en todo el territorio americano.<\/p>\n<p style=\"text-align: justify;\">La llegada de la orden religiosa de los mercedarios a\u00a0Am\u00e9rica, un poco relacionada con el antiguo esp\u00edritu de los caballeros que fueron a las Cruzadas a Tierra Santa y juntamente con el culto de la Virgen Compasiva, coincide con el poblamiento de las principales ciudades andinas cercanas a la l\u00ednea ecuatorial como son:\u00a0Cuzco,\u00a0Lima,\u00a0Quito,\u00a0Paita\u00a0y la Villaviciosa de la Concepci\u00f3n o\u00a0San Juan de Pasto, a pesar de que esta \u00faltima ten\u00eda como patrona religiosa a la Pura y Limpia Concepci\u00f3n, como su nombre lo indica. El Convento Mercedario primeramente se funda en\u00a0Santiago de Cali\u00a0hacia 1536 y en Pasto hacia 1545 y la iglesia anexa desde 1550, volvi\u00e9ndose muy famoso el ornato de este templo con una puerta labrada con leones dorados en su parte superior, imitando a los que fueron concedidos, junto con el t\u00edtulo de ciudad y el sobrenombre de\u00a0San Juan Bautista, a la Villa de Pasto. Es conocida popularmente en\u00a0San Juan de Pasto\u00a0como la Mechita Linda.<\/p>\n<p style=\"text-align: justify;\">Es en el siglo XVIII, de acuerdo al minucioso relato de\u00a0Jos\u00e9 Rafael Sa\u00f1udo, cuando la Virgen de las Mercedes aparece como protectora del Cabildo y pueblo de\u00a0San Juan de Pasto\u00a0respecto de erupciones y terremotos y otros eventos naturales da\u00f1inos. De hecho empieza a figurar la graciosa imagen como si fuera la que tiene el mando o el gobierno de Pasto. Son la fuerza de la tradici\u00f3n oral as\u00ed sustentada y, en parte, el sincretismo o mestizaje religioso que la acompa\u00f1a, los factores por los cuales se puede considerar a la Virgen de las Mercedes como Gobernadora de la Ciudad y no porque alguna autoridad civil en el siglo XX lo haya establecido por decreto. En 1612 se complet\u00f3 el templo de la Merced en Pasto y el trabajo en madera ocup\u00f3 a los artesanos y escultores L\u00e1zaro de Vergara (las dos puertas talladas, tirantes para los alfarjes de tipo mud\u00e9jar en la nave y el presbiterio), Rodrigo de Chaves (canter\u00eda de la portada y esculturas), el batihoja y doradores Juan de Echeverri, Francisco Gallardo y Francisco Ben\u00edtez, m\u00e1s el tabern\u00e1culo de tres cuerpos realizado por G\u00f3mez de Rojas en 1660.<\/p>\n<p style=\"text-align: justify;\">Per\u00fa\u00a0es actualmente el pa\u00eds que re\u00fane a la mayor cantidad de fieles de toda Am\u00e9rica y que cada 24 de septiembre celebran esta fiesta en honor a la Bienaventurada Virgen Mar\u00eda, en especial en la Peregrinaci\u00f3n Nacional e Internacional hacia el puerto de\u00a0Paita.<\/p>\n<p style=\"text-align: justify;\">La devoci\u00f3n a la Virgen de la Merced se difundi\u00f3 en\u00a0Bolivia, en el departamento de\u00a0La Paz, donde hoy se le rinde veneraci\u00f3n. Al a\u00f1o se le cambia tres veces sus vestiduras; la primera vez que se le cambia es la fecha del 3 de agosto recordando la primera vez que derram\u00f3 l\u00e1grimas, la segunda vez el 24 de septiembre recordando su fiesta y la tercera y \u00faltima vez en Navidad como regalo a su devoci\u00f3n. El 24 de septiembre en la Iglesia de la Merced se celebra una eucarist\u00eda de fiesta, nueve d\u00edas antes se le reza la novena y al finalizar existe una gran procesi\u00f3n en su honor. En Potos\u00ed, se celebra una solemne y lucida fiesta organizada por la Archicofrad\u00eda de Nuestra Se\u00f1ora de La Merced, instituci\u00f3n fundada en 1730 y que lleg\u00f3 a cobijar en el siglo XVIII a 10.000 cofrades.<\/p>\n<div class=\"sharedaddy sd-sharing-enabled\"><div class=\"robots-nocontent sd-block sd-social sd-social-icon sd-sharing\"><h3 class=\"sd-title\">Comparte esto:<\/h3><div class=\"sd-content\"><ul><li class=\"share-facebook\"><a rel=\"nofollow noopener noreferrer\" data-shared=\"sharing-facebook-18621\" class=\"share-facebook sd-button share-icon no-text\" href=\"http:\/\/www.hondurasensusmanos.com\/turismo\/el-24-de-septiembre-el-municipio-de-veracruz-copan-celebra-en-honor-a-la-virgen-de-la-merced\/?share=facebook\" target=\"_blank\" title=\"Haz clic para compartir en Facebook\"><span><\/span><span class=\"sharing-screen-reader-text\">Haz clic para compartir en Facebook (Se abre en una ventana nueva)<\/span><\/a><\/li><li class=\"share-jetpack-whatsapp\"><a rel=\"nofollow noopener noreferrer\" data-shared=\"\" class=\"share-jetpack-whatsapp sd-button share-icon no-text\" href=\"http:\/\/www.hondurasensusmanos.com\/turismo\/el-24-de-septiembre-el-municipio-de-veracruz-copan-celebra-en-honor-a-la-virgen-de-la-merced\/?share=jetpack-whatsapp\" target=\"_blank\" title=\"Haz clic para compartir en WhatsApp\"><span><\/span><span class=\"sharing-screen-reader-text\">Haz clic para compartir en WhatsApp (Se abre en una ventana nueva)<\/span><\/a><\/li><li class=\"share-twitter\"><a rel=\"nofollow noopener noreferrer\" data-shared=\"sharing-twitter-18621\" class=\"share-twitter sd-button share-icon no-text\" href=\"http:\/\/www.hondurasensusmanos.com\/turismo\/el-24-de-septiembre-el-municipio-de-veracruz-copan-celebra-en-honor-a-la-virgen-de-la-merced\/?share=twitter\" target=\"_blank\" title=\"Haz clic para compartir en Twitter\"><span><\/span><span class=\"sharing-screen-reader-text\">Haz clic para compartir en Twitter (Se abre en una ventana nueva)<\/span><\/a><\/li><li class=\"share-tumblr\"><a rel=\"nofollow noopener noreferrer\" data-shared=\"\" class=\"share-tumblr sd-button share-icon no-text\" href=\"http:\/\/www.hondurasensusmanos.com\/turismo\/el-24-de-septiembre-el-municipio-de-veracruz-copan-celebra-en-honor-a-la-virgen-de-la-merced\/?share=tumblr\" target=\"_blank\" title=\"Haz clic para compartir en Tumblr\"><span><\/span><span class=\"sharing-screen-reader-text\">Haz clic para compartir en Tumblr (Se abre en una ventana nueva)<\/span><\/a><\/li><li class=\"share-email\"><a rel=\"nofollow noopener noreferrer\" data-shared=\"\" class=\"share-email sd-button share-icon no-text\" href=\"http:\/\/www.hondurasensusmanos.com\/turismo\/el-24-de-septiembre-el-municipio-de-veracruz-copan-celebra-en-honor-a-la-virgen-de-la-merced\/?share=email\" target=\"_blank\" title=\"Haz clic para enviar por correo electr\u00f3nico a un amigo\"><span><\/span><span class=\"sharing-screen-reader-text\">Haz clic para enviar por correo electr\u00f3nico a un amigo (Se abre en una ventana nueva)<\/span><\/a><\/li><li class=\"share-end\"><\/li><\/ul><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Veracruz\u00a0es una\u00a0municipalidad\u00a0en el\u00a0departamento\u00a0de\u00a0Cop\u00e1n, en la rep\u00fablica de\u00a0Honduras. En la Divisi\u00f3n Pol\u00edtica de 1896 figuraba como Aldea del Municipio de San Jos\u00e9; antiguamente era la Aldea de Quetuna; el 3 de junio de 1902, los vecinos de dicha Aldea piden la creaci\u00f3n de un nuevo Municipio, Erigese en Municipio la Aldea de Veracruz, comprendida en la &#8230;<\/p>\n<div class=\"sharedaddy sd-sharing-enabled\"><div class=\"robots-nocontent sd-block sd-social sd-social-icon sd-sharing\"><h3 class=\"sd-title\">Comparte esto:<\/h3><div class=\"sd-content\"><ul><li class=\"share-facebook\"><a rel=\"nofollow noopener noreferrer\" data-shared=\"sharing-facebook-18621\" class=\"share-facebook sd-button share-icon no-text\" href=\"http:\/\/www.hondurasensusmanos.com\/turismo\/el-24-de-septiembre-el-municipio-de-veracruz-copan-celebra-en-honor-a-la-virgen-de-la-merced\/?share=facebook\" target=\"_blank\" title=\"Haz clic para compartir en Facebook\"><span><\/span><span class=\"sharing-screen-reader-text\">Haz clic para compartir en Facebook (Se abre en una ventana nueva)<\/span><\/a><\/li><li class=\"share-jetpack-whatsapp\"><a rel=\"nofollow noopener noreferrer\" data-shared=\"\" class=\"share-jetpack-whatsapp sd-button share-icon no-text\" href=\"http:\/\/www.hondurasensusmanos.com\/turismo\/el-24-de-septiembre-el-municipio-de-veracruz-copan-celebra-en-honor-a-la-virgen-de-la-merced\/?share=jetpack-whatsapp\" target=\"_blank\" title=\"Haz clic para compartir en WhatsApp\"><span><\/span><span class=\"sharing-screen-reader-text\">Haz clic para compartir en WhatsApp (Se abre en una ventana nueva)<\/span><\/a><\/li><li class=\"share-twitter\"><a rel=\"nofollow noopener noreferrer\" data-shared=\"sharing-twitter-18621\" class=\"share-twitter sd-button share-icon no-text\" href=\"http:\/\/www.hondurasensusmanos.com\/turismo\/el-24-de-septiembre-el-municipio-de-veracruz-copan-celebra-en-honor-a-la-virgen-de-la-merced\/?share=twitter\" target=\"_blank\" title=\"Haz clic para compartir en Twitter\"><span><\/span><span class=\"sharing-screen-reader-text\">Haz clic para compartir en Twitter (Se abre en una ventana nueva)<\/span><\/a><\/li><li class=\"share-tumblr\"><a rel=\"nofollow noopener noreferrer\" data-shared=\"\" class=\"share-tumblr sd-button share-icon no-text\" href=\"http:\/\/www.hondurasensusmanos.com\/turismo\/el-24-de-septiembre-el-municipio-de-veracruz-copan-celebra-en-honor-a-la-virgen-de-la-merced\/?share=tumblr\" target=\"_blank\" title=\"Haz clic para compartir en Tumblr\"><span><\/span><span class=\"sharing-screen-reader-text\">Haz clic para compartir en Tumblr (Se abre en una ventana nueva)<\/span><\/a><\/li><li class=\"share-email\"><a rel=\"nofollow noopener noreferrer\" data-shared=\"\" class=\"share-email sd-button share-icon no-text\" href=\"http:\/\/www.hondurasensusmanos.com\/turismo\/el-24-de-septiembre-el-municipio-de-veracruz-copan-celebra-en-honor-a-la-virgen-de-la-merced\/?share=email\" target=\"_blank\" title=\"Haz clic para enviar por correo electr\u00f3nico a un amigo\"><span><\/span><span class=\"sharing-screen-reader-text\">Haz clic para enviar por correo electr\u00f3nico a un amigo (Se abre en una ventana nueva)<\/span><\/a><\/li><li class=\"share-end\"><\/li><\/ul><\/div><\/div><\/div>","protected":false},"author":4,"featured_media":18623,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false},"categories":[69,41,65],"tags":[],"jetpack_featured_media_url":"http:\/\/www.hondurasensusmanos.com\/turismo\/wp-content\/uploads\/2021\/06\/veracruz-copannn.jpg","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8AciD-4Ql","_links":{"self":[{"href":"http:\/\/www.hondurasensusmanos.com\/turismo\/wp-json\/wp\/v2\/posts\/18621"}],"collection":[{"href":"http:\/\/www.hondurasensusmanos.com\/turismo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.hondurasensusmanos.com\/turismo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.hondurasensusmanos.com\/turismo\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.hondurasensusmanos.com\/turismo\/wp-json\/wp\/v2\/comments?post=18621"}],"version-history":[{"count":2,"href":"http:\/\/www.hondurasensusmanos.com\/turismo\/wp-json\/wp\/v2\/posts\/18621\/revisions"}],"predecessor-version":[{"id":18625,"href":"http:\/\/www.hondurasensusmanos.com\/turismo\/wp-json\/wp\/v2\/posts\/18621\/revisions\/18625"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.hondurasensusmanos.com\/turismo\/wp-json\/wp\/v2\/media\/18623"}],"wp:attachment":[{"href":"http:\/\/www.hondurasensusmanos.com\/turismo\/wp-json\/wp\/v2\/media?parent=18621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.hondurasensusmanos.com\/turismo\/wp-json\/wp\/v2\/categories?post=18621"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.hondurasensusmanos.com\/turismo\/wp-json\/wp\/v2\/tags?post=18621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}