{"id":23125,"date":"2024-10-25T04:55:29","date_gmt":"2024-10-24T17:25:29","guid":{"rendered":"https:\/\/www.hondurasensusmanos.com\/turismo\/?p=23125"},"modified":"2024-10-25T04:55:29","modified_gmt":"2024-10-24T17:25:29","slug":"iht-promueve-las-cataratas-de-pulhapanzak","status":"publish","type":"post","link":"https:\/\/www.hondurasensusmanos.com\/turismo\/iht-promueve-las-cataratas-de-pulhapanzak\/","title":{"rendered":"IHT promueve las Cataratas de Pulhapanzak"},"content":{"rendered":"<p><a href=\"http:\/\/www.hondurasensusmanos.com\/turismo\/wp-content\/uploads\/2024\/10\/day-trip-to-pulhapanzak-waterfall-and-yojoa-lake-from-san-pedro-sula-in-san-pedro-sula-292720-674x430-1.jpg\"><img loading=\"lazy\" class=\"alignnone size-medium wp-image-23126\" src=\"http:\/\/www.hondurasensusmanos.com\/turismo\/wp-content\/uploads\/2024\/10\/day-trip-to-pulhapanzak-waterfall-and-yojoa-lake-from-san-pedro-sula-in-san-pedro-sula-292720-674x430-1-300x191.jpg\" alt=\"\" width=\"300\" height=\"191\" srcset=\"https:\/\/www.hondurasensusmanos.com\/turismo\/wp-content\/uploads\/2024\/10\/day-trip-to-pulhapanzak-waterfall-and-yojoa-lake-from-san-pedro-sula-in-san-pedro-sula-292720-674x430-1-300x191.jpg 300w, https:\/\/www.hondurasensusmanos.com\/turismo\/wp-content\/uploads\/2024\/10\/day-trip-to-pulhapanzak-waterfall-and-yojoa-lake-from-san-pedro-sula-in-san-pedro-sula-292720-674x430-1.jpg 674w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><strong>24. 10.24<\/strong><\/p>\n<p>El nacimiento de las Cataratas de Pulhapanzak, situada al norte del Lago de Yojoa, ofrece uno de sus principales atractivos con un tour al manantial, donde comienza la magia de la famosa cascada del lugar. El manantial tiene profundidades que var\u00edan entre seis y siete metros y alberga una caverna cuya profundidad exacta a\u00fan no ha sido explorada.<\/p>\n<p>Pulhapanzak cuenta con seis caba\u00f1as disponibles para quienes deseen desconectarse y disfrutar de la naturaleza, los hu\u00e9spedes tienen acceso a actividades como canopy, caminatas detr\u00e1s de la catarata, river tubing y visitas al nacimiento del r\u00edo. Tambi\u00e9n existe la opci\u00f3n de pasar el d\u00eda en el parque por 120 lempiras por adulto, lo que incluye el acceso al estacionamiento, la vista desde el mirador de la cascada, y la oportunidad de ba\u00f1arse en las pozas del r\u00edo.<\/p>\n<p>Pulhapanzak es ideal para disfrutar momentos especiales en contacto con la naturaleza junto a familiares y amigos.<\/p>\n<p>Fuente: Diario Roat\u00e1n.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div class=\"sharedaddy sd-sharing-enabled\"><div class=\"robots-nocontent sd-block sd-social sd-social-icon sd-sharing\"><h3 class=\"sd-title\">Comparte esto:<\/h3><div class=\"sd-content\"><ul><li class=\"share-facebook\"><a rel=\"nofollow noopener noreferrer\" data-shared=\"sharing-facebook-23125\" class=\"share-facebook sd-button share-icon no-text\" href=\"https:\/\/www.hondurasensusmanos.com\/turismo\/iht-promueve-las-cataratas-de-pulhapanzak\/?share=facebook\" target=\"_blank\" title=\"Haz clic para compartir en Facebook\"><span><\/span><span class=\"sharing-screen-reader-text\">Haz clic para compartir en Facebook (Se abre en una ventana nueva)<\/span><\/a><\/li><li class=\"share-jetpack-whatsapp\"><a rel=\"nofollow noopener noreferrer\" data-shared=\"\" class=\"share-jetpack-whatsapp sd-button share-icon no-text\" href=\"https:\/\/www.hondurasensusmanos.com\/turismo\/iht-promueve-las-cataratas-de-pulhapanzak\/?share=jetpack-whatsapp\" target=\"_blank\" title=\"Haz clic para compartir en WhatsApp\"><span><\/span><span class=\"sharing-screen-reader-text\">Haz clic para compartir en WhatsApp (Se abre en una ventana nueva)<\/span><\/a><\/li><li class=\"share-twitter\"><a rel=\"nofollow noopener noreferrer\" data-shared=\"sharing-twitter-23125\" class=\"share-twitter sd-button share-icon no-text\" href=\"https:\/\/www.hondurasensusmanos.com\/turismo\/iht-promueve-las-cataratas-de-pulhapanzak\/?share=twitter\" target=\"_blank\" title=\"Haz clic para compartir en Twitter\"><span><\/span><span class=\"sharing-screen-reader-text\">Haz clic para compartir en Twitter (Se abre en una ventana nueva)<\/span><\/a><\/li><li class=\"share-tumblr\"><a rel=\"nofollow noopener noreferrer\" data-shared=\"\" class=\"share-tumblr sd-button share-icon no-text\" href=\"https:\/\/www.hondurasensusmanos.com\/turismo\/iht-promueve-las-cataratas-de-pulhapanzak\/?share=tumblr\" target=\"_blank\" title=\"Haz clic para compartir en Tumblr\"><span><\/span><span class=\"sharing-screen-reader-text\">Haz clic para compartir en Tumblr (Se abre en una ventana nueva)<\/span><\/a><\/li><li class=\"share-email\"><a rel=\"nofollow noopener noreferrer\" data-shared=\"\" class=\"share-email sd-button share-icon no-text\" href=\"https:\/\/www.hondurasensusmanos.com\/turismo\/iht-promueve-las-cataratas-de-pulhapanzak\/?share=email\" target=\"_blank\" title=\"Haz clic para enviar por correo electr\u00f3nico a un amigo\"><span><\/span><span class=\"sharing-screen-reader-text\">Haz clic para enviar por correo electr\u00f3nico a un amigo (Se abre en una ventana nueva)<\/span><\/a><\/li><li class=\"share-end\"><\/li><\/ul><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>24. 10.24 El nacimiento de las Cataratas de Pulhapanzak, situada al norte del Lago de Yojoa, ofrece uno de sus principales atractivos con un tour al manantial, donde comienza la magia de la famosa cascada del lugar. El manantial tiene profundidades que var\u00edan entre seis y siete metros y alberga una caverna cuya profundidad exacta &#8230;<\/p>\n<div class=\"sharedaddy sd-sharing-enabled\"><div class=\"robots-nocontent sd-block sd-social sd-social-icon sd-sharing\"><h3 class=\"sd-title\">Comparte esto:<\/h3><div class=\"sd-content\"><ul><li class=\"share-facebook\"><a rel=\"nofollow noopener noreferrer\" data-shared=\"sharing-facebook-23125\" class=\"share-facebook sd-button share-icon no-text\" href=\"https:\/\/www.hondurasensusmanos.com\/turismo\/iht-promueve-las-cataratas-de-pulhapanzak\/?share=facebook\" target=\"_blank\" title=\"Haz clic para compartir en Facebook\"><span><\/span><span class=\"sharing-screen-reader-text\">Haz clic para compartir en Facebook (Se abre en una ventana nueva)<\/span><\/a><\/li><li class=\"share-jetpack-whatsapp\"><a rel=\"nofollow noopener noreferrer\" data-shared=\"\" class=\"share-jetpack-whatsapp sd-button share-icon no-text\" href=\"https:\/\/www.hondurasensusmanos.com\/turismo\/iht-promueve-las-cataratas-de-pulhapanzak\/?share=jetpack-whatsapp\" target=\"_blank\" title=\"Haz clic para compartir en WhatsApp\"><span><\/span><span class=\"sharing-screen-reader-text\">Haz clic para compartir en WhatsApp (Se abre en una ventana nueva)<\/span><\/a><\/li><li class=\"share-twitter\"><a rel=\"nofollow noopener noreferrer\" data-shared=\"sharing-twitter-23125\" class=\"share-twitter sd-button share-icon no-text\" href=\"https:\/\/www.hondurasensusmanos.com\/turismo\/iht-promueve-las-cataratas-de-pulhapanzak\/?share=twitter\" target=\"_blank\" title=\"Haz clic para compartir en Twitter\"><span><\/span><span class=\"sharing-screen-reader-text\">Haz clic para compartir en Twitter (Se abre en una ventana nueva)<\/span><\/a><\/li><li class=\"share-tumblr\"><a rel=\"nofollow noopener noreferrer\" data-shared=\"\" class=\"share-tumblr sd-button share-icon no-text\" href=\"https:\/\/www.hondurasensusmanos.com\/turismo\/iht-promueve-las-cataratas-de-pulhapanzak\/?share=tumblr\" target=\"_blank\" title=\"Haz clic para compartir en Tumblr\"><span><\/span><span class=\"sharing-screen-reader-text\">Haz clic para compartir en Tumblr (Se abre en una ventana nueva)<\/span><\/a><\/li><li class=\"share-email\"><a rel=\"nofollow noopener noreferrer\" data-shared=\"\" class=\"share-email sd-button share-icon no-text\" href=\"https:\/\/www.hondurasensusmanos.com\/turismo\/iht-promueve-las-cataratas-de-pulhapanzak\/?share=email\" target=\"_blank\" title=\"Haz clic para enviar por correo electr\u00f3nico a un amigo\"><span><\/span><span class=\"sharing-screen-reader-text\">Haz clic para enviar por correo electr\u00f3nico a un amigo (Se abre en una ventana nueva)<\/span><\/a><\/li><li class=\"share-end\"><\/li><\/ul><\/div><\/div><\/div>","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false},"categories":[63],"tags":[],"jetpack_featured_media_url":"","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8AciD-60Z","_links":{"self":[{"href":"https:\/\/www.hondurasensusmanos.com\/turismo\/wp-json\/wp\/v2\/posts\/23125"}],"collection":[{"href":"https:\/\/www.hondurasensusmanos.com\/turismo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hondurasensusmanos.com\/turismo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hondurasensusmanos.com\/turismo\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hondurasensusmanos.com\/turismo\/wp-json\/wp\/v2\/comments?post=23125"}],"version-history":[{"count":1,"href":"https:\/\/www.hondurasensusmanos.com\/turismo\/wp-json\/wp\/v2\/posts\/23125\/revisions"}],"predecessor-version":[{"id":23127,"href":"https:\/\/www.hondurasensusmanos.com\/turismo\/wp-json\/wp\/v2\/posts\/23125\/revisions\/23127"}],"wp:attachment":[{"href":"https:\/\/www.hondurasensusmanos.com\/turismo\/wp-json\/wp\/v2\/media?parent=23125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hondurasensusmanos.com\/turismo\/wp-json\/wp\/v2\/categories?post=23125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hondurasensusmanos.com\/turismo\/wp-json\/wp\/v2\/tags?post=23125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}